
{"id":3906,"count":1,"description":"","link":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/","name":"Gender Equality Paradox","slug":"gender-equality-paradox-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gender Equality Paradox Archives - University Post<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gender Equality Paradox Archives - University Post\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/\" \/>\n<meta property=\"og:site_name\" content=\"University Post\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Uniavisen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/uniavisen.dk\\\/en\\\/tag\\\/gender-equality-paradox-en\\\/\",\"url\":\"https:\\\/\\\/uniavisen.dk\\\/en\\\/tag\\\/gender-equality-paradox-en\\\/\",\"name\":\"Gender Equality Paradox Archives - University Post\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniavisen.dk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniavisen.dk\\\/en\\\/tag\\\/gender-equality-paradox-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniavisen.dk\\\/en\\\/tag\\\/gender-equality-paradox-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uniavisen.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gender Equality Paradox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniavisen.dk\\\/#website\",\"url\":\"https:\\\/\\\/uniavisen.dk\\\/\",\"name\":\"University Post\",\"description\":\"Independent of management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniavisen.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gender Equality Paradox Archives - University Post","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Gender Equality Paradox Archives - University Post","og_url":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/","og_site_name":"University Post","twitter_card":"summary_large_image","twitter_site":"@Uniavisen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/","url":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/","name":"Gender Equality Paradox Archives - University Post","isPartOf":{"@id":"https:\/\/uniavisen.dk\/#website"},"breadcrumb":{"@id":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/uniavisen.dk\/en\/tag\/gender-equality-paradox-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uniavisen.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Gender Equality Paradox"}]},{"@type":"WebSite","@id":"https:\/\/uniavisen.dk\/#website","url":"https:\/\/uniavisen.dk\/","name":"University Post","description":"Independent of management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniavisen.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/uniavisen.dk\/en\/wp-json\/wp\/v2\/tags\/3906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniavisen.dk\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/uniavisen.dk\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/uniavisen.dk\/en\/wp-json\/wp\/v2\/posts?tags=3906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}